{"id":49126,"date":"2026-04-15T16:39:21","date_gmt":"2026-04-15T14:39:21","guid":{"rendered":"https:\/\/www.black-jaguar.org\/?p=49126"},"modified":"2026-04-15T16:39:21","modified_gmt":"2026-04-15T14:39:21","slug":"articulacao-1-trimestre-2026","status":"publish","type":"post","link":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/","title":{"rendered":"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026<\/strong><\/p>\n<p><em>Saiba mais sobre o trabalho de articula\u00e7\u00e3o de parcerias<\/em><\/p>\n<p>No \u00e2mbito de Parcerias Rurais, foram realizadas as seguintes a\u00e7\u00f5es:<\/p>\n<p><strong>Valida\u00e7\u00e3o e Parcerias<\/strong><strong>:<\/strong><\/p>\n<ul>\n<li>Na segunda semana de janeiro, foi realizada reuni\u00e3o com a propriet\u00e1ria da fazenda 22, para acompanhar o andamento da implanta\u00e7\u00e3o. Na ocasi\u00e3o, os propriet\u00e1rios manifestaram interesse em cancelar algumas \u00e1reas previamente aprovadas. Durante a conversa, foi poss\u00edvel esclarecer a import\u00e2ncia da restaura\u00e7\u00e3o de todos os pontos com passivos ambientais, tanto sob o aspecto ambiental quanto no que se refere \u00e0 regulariza\u00e7\u00e3o da propriedade. Ao final, a relev\u00e2ncia das interven\u00e7\u00f5es foi compreendida, sendo autorizada a conclus\u00e3o da implanta\u00e7\u00e3o na propriedade.<\/li>\n<li>Na mesma semana, a equipe de Parcerias Rurais esteve na Fazenda 11, com o objetivo de acompanhar as \u00e1reas j\u00e1 implantadas e apresentar registros das atividades realizadas ao propriet\u00e1rio.<\/li>\n<\/ul>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flexslider_style&#8221; images=&#8221;49127,49128&#8243; onclick=&#8221;link_no&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li>Ainda em janeiro, foi realizada reuni\u00e3o com o propriet\u00e1rio da Fazenda 25, com a finalidade de tratar das \u00e1reas implantadas e compreender a percep\u00e7\u00e3o do produtor rural sobre o trabalho de restaura\u00e7\u00e3o ecol\u00f3gica desenvolvido.<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li>Em mar\u00e7o, o time se reuniu com o propriet\u00e1rio da Fazenda 13, ocasi\u00e3o em que o produtor apresentou questionamentos relacionados \u00e0 \u00e1rea implantada no ciclo atual, bem como buscou esclarecimentos sobre o passivo ambiental existente na propriedade. Durante a reuni\u00e3o, foram apresentados e esclarecidos os limites das \u00c1reas de Preserva\u00e7\u00e3o Permanente (APPs), destacando-se sua import\u00e2ncia sob a \u00f3tica ambiental e os aspectos de conformidade e seguran\u00e7a jur\u00eddica perante o \u00f3rg\u00e3o ambiental competente. Na oportunidade, tamb\u00e9m foi informado que a propriedade concluiu todas as etapas de implanta\u00e7\u00e3o do plantio, restando, neste momento, apenas a execu\u00e7\u00e3o das atividades de manuten\u00e7\u00e3o das \u00e1reas restauradas.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Na mesma semana, foi conduzida reuni\u00e3o o propriet\u00e1rio da Fazenda 25, para apresentar devolutiva referente \u00e0 \u00e1rea implantada no \u00faltimo ciclo, bem como discutir novas oportunidades de parceria. Na ocasi\u00e3o, o produtor demonstrou elevado n\u00edvel de satisfa\u00e7\u00e3o com os resultados alcan\u00e7ados at\u00e9 o momento. Ficou acordada a realiza\u00e7\u00e3o de um encontro presencial no m\u00eas de abril.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Para finalizar o trimestre, foi realizada visita \u00e0 Fazenda 22, com o objetivo de promover nova rodada de alinhamentos com a propriet\u00e1ria, visando esclarecer pontos relacionados \u00e0 manuten\u00e7\u00e3o das \u00e1reas implantadas.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Atividades institucionais:<\/strong><\/p>\n<ul>\n<li>Em janeiro, foi realizada nova visita \u00e0 Fazenda 22, com a finalidade de definir um local adequado para a realiza\u00e7\u00e3o de um plantio simb\u00f3lico, a\u00e7\u00e3o voltada ao engajamento do propriet\u00e1rio rural e de seus familiares.<\/li>\n<\/ul>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flexslider_style&#8221; images=&#8221;49129,49130&#8243; onclick=&#8221;link_no&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li>No dia 16, foi realizado o plantio simb\u00f3lico na Fazenda 22. Na oportunidade, participaram familiares do propriet\u00e1rio, bem como colaboradores do Instituto, configurando um momento de integra\u00e7\u00e3o da equipe, aproxima\u00e7\u00e3o com o produtor rural e fortalecimento das alian\u00e7as estabelecidas.<\/li>\n<\/ul>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flexslider_style&#8221; images=&#8221;49131,49132,49133,49134&#8243; onclick=&#8221;link_no&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li>No dia 21, os times IBJ e Planet Wild, organiza\u00e7\u00e3o alem\u00e3, estiveram na Fazenda 07, para realizar uma entrevista com o propriet\u00e1rio, em que pudesse expressar os pontos positivos e import\u00e2ncia da restaura\u00e7\u00e3o ecol\u00f3gica em sua propriedade.<\/li>\n<\/ul>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flexslider_style&#8221; images=&#8221;49135,49136&#8243; onclick=&#8221;link_no&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li>No in\u00edcio de fevereiro foi realizada reuni\u00e3o com o Secret\u00e1rio Municipal de Meio Ambiente para tratar do evento \u201cSemas Itinerante\u201d, promovido pelo Governo do Estado, com o objetivo de acelerar os processos de regulariza\u00e7\u00e3o ambiental no munic\u00edpio e apoiar pequenos produtores rurais. O evento foi identificado como oportunidade estrat\u00e9gica para prospec\u00e7\u00e3o de novos parceiros, especialmente junto aos produtores de Projetos de Assentamento (P.A.), segmento no qual t\u00eam sido observadas dificuldades de acesso \u00e0s iniciativas de restaura\u00e7\u00e3o.<\/li>\n<li>Assim, entre 24 e 25 de fevereiro o IBJ participou no evento municipal voltado \u00e0 regulariza\u00e7\u00e3o ambiental, no qual o principal objetivo foi estabelecer contato com lideran\u00e7as dos Projetos de Assentamento (P.A.) previamente definidos como estrat\u00e9gicos. A equipe esteve presente nos dois dias de programa\u00e7\u00e3o, ocasi\u00e3o em que foram alinhadas reuni\u00f5es com l\u00edderes comunit\u00e1rios para detalhamento do projeto voltado ao pequeno produtor rural.<\/li>\n<li>Al\u00e9m das lideran\u00e7as dos P.A.s, esteve presente o Sr. Raul Prot\u00e1zio, Secret\u00e1rio de Estado de Meio Ambiente e Sustentabilidade do Par\u00e1, com quem houve breve di\u00e1logo institucional sobre as atividades desenvolvidas pelo Instituto Black Jaguar.<\/li>\n<\/ul>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;flexslider_style&#8221; images=&#8221;49137,49138,49139,49140,49141,49142,49143,49144&#8243; onclick=&#8221;link_no&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Total da Meta 1.2 alcan\u00e7ado: 92,13%<em> (Reprograma\u00e7\u00e3o 5)<\/em><\/p>\n<p><em>As a\u00e7\u00f5es de mobiliza\u00e7\u00e3o comunit\u00e1ria, restaura\u00e7\u00e3o e manuten\u00e7\u00e3o de \u00e1reas degradadas na regi\u00e3o de Santana do Araguaia (PA) e Caseara (TO) fazem parte do programa Caixa Florestas, e s\u00e3o financiadas pelo Fundo Socioambiental CAIXA.<\/em><\/p>\n<p><strong>\u00a0<\/strong>[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":62,"featured_media":49144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[124],"tags":[],"class_list":["post-49126","post","type-post","status-publish","format-standard","has-post-thumbnail","category-caixa-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Black Jaguar Foundation\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T14:39:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.black-jaguar.org\/wp-content\/uploads\/2026\/04\/8-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"374\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Carolina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Carolina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/\"},\"author\":{\"name\":\"Ana Carolina\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/25cbc4abbca6b825f381dff6ced3bec7\"},\"headline\":\"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026\",\"datePublished\":\"2026-04-15T14:39:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/\"},\"wordCount\":2099,\"publisher\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.black-jaguar.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8-1.jpg\",\"articleSection\":[\"CAIXA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/\",\"url\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/\",\"name\":\"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.black-jaguar.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8-1.jpg\",\"datePublished\":\"2026-04-15T14:39:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.black-jaguar.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.black-jaguar.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8-1.jpg\",\"width\":560,\"height\":374},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/articulacao-1-trimestre-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/\",\"name\":\"Black Jaguar Foundation\",\"description\":\"realising the largest biodiversity corridor on earth\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#organization\",\"name\":\"Black Jaguar Foundation\",\"url\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.black-jaguar.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/2.-PNG_BJF_LOGO_21_April_2020-1.png\",\"contentUrl\":\"https:\\\/\\\/www.black-jaguar.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/2.-PNG_BJF_LOGO_21_April_2020-1.png\",\"width\":519,\"height\":537,\"caption\":\"Black Jaguar Foundation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/25cbc4abbca6b825f381dff6ced3bec7\",\"name\":\"Ana Carolina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55655b0b8c8f2aadf11f1b53631b06962e3ce49e25b7be24aae4b26173e8f6ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55655b0b8c8f2aadf11f1b53631b06962e3ce49e25b7be24aae4b26173e8f6ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55655b0b8c8f2aadf11f1b53631b06962e3ce49e25b7be24aae4b26173e8f6ef?s=96&d=mm&r=g\",\"caption\":\"Ana Carolina\"},\"url\":\"https:\\\/\\\/www.black-jaguar.org\\\/pt-br\\\/author\\\/a-pratesblack-jaguar-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/","og_site_name":"Black Jaguar Foundation","article_published_time":"2026-04-15T14:39:21+00:00","og_image":[{"width":560,"height":374,"url":"https:\/\/www.black-jaguar.org\/wp-content\/uploads\/2026\/04\/8-1.jpg","type":"image\/jpeg"}],"author":"Ana Carolina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana Carolina","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/#article","isPartOf":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/"},"author":{"name":"Ana Carolina","@id":"https:\/\/www.black-jaguar.org\/pt-br\/#\/schema\/person\/25cbc4abbca6b825f381dff6ced3bec7"},"headline":"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026","datePublished":"2026-04-15T14:39:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/"},"wordCount":2099,"publisher":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.black-jaguar.org\/wp-content\/uploads\/2026\/04\/8-1.jpg","articleSection":["CAIXA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/","url":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/","name":"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026","isPartOf":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.black-jaguar.org\/wp-content\/uploads\/2026\/04\/8-1.jpg","datePublished":"2026-04-15T14:39:21+00:00","breadcrumb":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/#primaryimage","url":"https:\/\/www.black-jaguar.org\/wp-content\/uploads\/2026\/04\/8-1.jpg","contentUrl":"https:\/\/www.black-jaguar.org\/wp-content\/uploads\/2026\/04\/8-1.jpg","width":560,"height":374},{"@type":"BreadcrumbList","@id":"https:\/\/www.black-jaguar.org\/pt-br\/articulacao-1-trimestre-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.black-jaguar.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Atividades da equipe de articula\u00e7\u00e3o de parcerias no 1\u00ba trimestre de 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.black-jaguar.org\/pt-br\/#website","url":"https:\/\/www.black-jaguar.org\/pt-br\/","name":"Black Jaguar Foundation","description":"realising the largest biodiversity corridor on earth","publisher":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.black-jaguar.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.black-jaguar.org\/pt-br\/#organization","name":"Black Jaguar Foundation","url":"https:\/\/www.black-jaguar.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.black-jaguar.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.black-jaguar.org\/wp-content\/uploads\/2021\/07\/2.-PNG_BJF_LOGO_21_April_2020-1.png","contentUrl":"https:\/\/www.black-jaguar.org\/wp-content\/uploads\/2021\/07\/2.-PNG_BJF_LOGO_21_April_2020-1.png","width":519,"height":537,"caption":"Black Jaguar Foundation"},"image":{"@id":"https:\/\/www.black-jaguar.org\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.black-jaguar.org\/pt-br\/#\/schema\/person\/25cbc4abbca6b825f381dff6ced3bec7","name":"Ana Carolina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/55655b0b8c8f2aadf11f1b53631b06962e3ce49e25b7be24aae4b26173e8f6ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55655b0b8c8f2aadf11f1b53631b06962e3ce49e25b7be24aae4b26173e8f6ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55655b0b8c8f2aadf11f1b53631b06962e3ce49e25b7be24aae4b26173e8f6ef?s=96&d=mm&r=g","caption":"Ana Carolina"},"url":"https:\/\/www.black-jaguar.org\/pt-br\/author\/a-pratesblack-jaguar-org\/"}]}},"_links":{"self":[{"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/posts\/49126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/comments?post=49126"}],"version-history":[{"count":1,"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/posts\/49126\/revisions"}],"predecessor-version":[{"id":49145,"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/posts\/49126\/revisions\/49145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/media\/49144"}],"wp:attachment":[{"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/media?parent=49126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/categories?post=49126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.black-jaguar.org\/pt-br\/wp-json\/wp\/v2\/tags?post=49126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}